{"id":2114,"count":8,"description":"","link":"https:\/\/www.platinambalaje.ro\/en\/categorie\/trash-bags\/","name":"Trash bags","slug":"trash-bags","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":60,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arhive Trash bags - PLATIN AMBALAJE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.platinambalaje.ro\/en\/categorie\/trash-bags\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arhive Trash bags - PLATIN AMBALAJE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.platinambalaje.ro\/en\/categorie\/trash-bags\/\" \/>\n<meta property=\"og:site_name\" content=\"PLATIN AMBALAJE\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.platinambalaje.ro\/wp-content\/uploads\/2023\/03\/banner-yoast.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.platinambalaje.ro\\\/en\\\/categorie\\\/trash-bags\\\/\",\"url\":\"https:\\\/\\\/www.platinambalaje.ro\\\/en\\\/categorie\\\/trash-bags\\\/\",\"name\":\"Arhive Trash bags - PLATIN AMBALAJE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.platinambalaje.ro\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.platinambalaje.ro\\\/en\\\/categorie\\\/trash-bags\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.platinambalaje.ro\\\/en\\\/categorie\\\/trash-bags\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Prima pagin\u0103\",\"item\":\"https:\\\/\\\/www.platinambalaje.ro\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trash bags\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.platinambalaje.ro\\\/#website\",\"url\":\"https:\\\/\\\/www.platinambalaje.ro\\\/\",\"name\":\"PLATIN AMBALAJE\",\"description\":\"EXPER\u021aII T\u0102I \u00ceN AMBALAJE\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.platinambalaje.ro\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.platinambalaje.ro\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.platinambalaje.ro\\\/#organization\",\"name\":\"Platin Ambalaje\",\"url\":\"https:\\\/\\\/www.platinambalaje.ro\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.platinambalaje.ro\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.platinambalaje.ro\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-retina.png\",\"contentUrl\":\"https:\\\/\\\/www.platinambalaje.ro\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/logo-retina.png\",\"width\":598,\"height\":251,\"caption\":\"Platin Ambalaje\"},\"image\":{\"@id\":\"https:\\\/\\\/www.platinambalaje.ro\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arhive Trash bags - PLATIN AMBALAJE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.platinambalaje.ro\/en\/categorie\/trash-bags\/","og_locale":"en_US","og_type":"article","og_title":"Arhive Trash bags - PLATIN AMBALAJE","og_url":"https:\/\/www.platinambalaje.ro\/en\/categorie\/trash-bags\/","og_site_name":"PLATIN AMBALAJE","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.platinambalaje.ro\/wp-content\/uploads\/2023\/03\/banner-yoast.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.platinambalaje.ro\/en\/categorie\/trash-bags\/","url":"https:\/\/www.platinambalaje.ro\/en\/categorie\/trash-bags\/","name":"Arhive Trash bags - PLATIN AMBALAJE","isPartOf":{"@id":"https:\/\/www.platinambalaje.ro\/#website"},"breadcrumb":{"@id":"https:\/\/www.platinambalaje.ro\/en\/categorie\/trash-bags\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.platinambalaje.ro\/en\/categorie\/trash-bags\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Prima pagin\u0103","item":"https:\/\/www.platinambalaje.ro\/en\/"},{"@type":"ListItem","position":2,"name":"Trash bags"}]},{"@type":"WebSite","@id":"https:\/\/www.platinambalaje.ro\/#website","url":"https:\/\/www.platinambalaje.ro\/","name":"PLATIN AMBALAJE","description":"EXPER\u021aII T\u0102I \u00ceN AMBALAJE","publisher":{"@id":"https:\/\/www.platinambalaje.ro\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.platinambalaje.ro\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.platinambalaje.ro\/#organization","name":"Platin Ambalaje","url":"https:\/\/www.platinambalaje.ro\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.platinambalaje.ro\/#\/schema\/logo\/image\/","url":"https:\/\/www.platinambalaje.ro\/wp-content\/uploads\/2023\/03\/logo-retina.png","contentUrl":"https:\/\/www.platinambalaje.ro\/wp-content\/uploads\/2023\/03\/logo-retina.png","width":598,"height":251,"caption":"Platin Ambalaje"},"image":{"@id":"https:\/\/www.platinambalaje.ro\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.platinambalaje.ro\/en\/wp-json\/wp\/v2\/product_cat\/2114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.platinambalaje.ro\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.platinambalaje.ro\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/www.platinambalaje.ro\/en\/wp-json\/wp\/v2\/product?product_cat=2114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}